{"id":6309,"date":"2025-04-17T07:35:04","date_gmt":"2025-04-17T07:35:04","guid":{"rendered":"https:\/\/online-application.co.in\/scie\/?page_id=6309"},"modified":"2025-08-29T10:17:46","modified_gmt":"2025-08-29T10:17:46","slug":"events-details-95","status":"publish","type":"page","link":"https:\/\/online-application.co.in\/scie\/events-details-95\/","title":{"rendered":"International Students&#8217; Day &#8211; Cultural Dance Competition"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6309\" class=\"elementor elementor-6309\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f542168 e-flex e-con-boxed e-con e-parent\" data-id=\"f542168\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-93e6fb4 e-con-full e-flex e-con e-child\" data-id=\"93e6fb4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-e310ec2 e-con-full e-flex e-con e-child\" data-id=\"e310ec2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4cb348f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4cb348f\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-home\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M280.37 148.26L96 300.11V464a16 16 0 0 0 16 16l112.06-.29a16 16 0 0 0 15.92-16V368a16 16 0 0 1 16-16h64a16 16 0 0 1 16 16v95.64a16 16 0 0 0 16 16.05L464 480a16 16 0 0 0 16-16V300L295.67 148.26a12.19 12.19 0 0 0-15.3 0zM571.6 251.47L488 182.56V44.05a12 12 0 0 0-12-12h-56a12 12 0 0 0-12 12v72.61L318.47 43a48 48 0 0 0-61 0L4.34 251.47a12 12 0 0 0-1.6 16.9l25.5 31A12 12 0 0 0 45.15 301l235.22-193.74a12.19 12.19 0 0 1 15.3 0L530.9 301a12 12 0 0 0 16.9-1.6l25.5-31a12 12 0 0 0-1.7-16.93z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cfe0f2 elementor-widget elementor-widget-heading\" data-id=\"5cfe0f2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/online-application.co.in\/scie\">Home<\/a> \/\n<a href=\"https:\/\/online-application.co.in\/scie\/life-at-symbiosis\/\">Life @Symbiosis<\/a> \/ \nInternational Students' Day - Cultural Dance Competition<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92dfd0a gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"92dfd0a\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-6309 gallery-columns-3 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"92dfd0a\" data-elementor-lightbox-title=\"7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjMyMywidXJsIjoiaHR0cHM6XC9cL29ubGluZS1hcHBsaWNhdGlvbi5jby5pblwvc2NpZVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDRcLzctOC5wbmciLCJzbGlkZXNob3ciOiI5MmRmZDBhIn0%3D\" href='https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/7-8.png'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/7-8.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/7-8.png 640w, https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/7-8-300x200.png 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"92dfd0a\" data-elementor-lightbox-title=\"5\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjMyMSwidXJsIjoiaHR0cHM6XC9cL29ubGluZS1hcHBsaWNhdGlvbi5jby5pblwvc2NpZVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDRcLzUtMTIucG5nIiwic2xpZGVzaG93IjoiOTJkZmQwYSJ9\" href='https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/5-12.png'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/5-12.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/5-12.png 640w, https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/5-12-300x200.png 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"92dfd0a\" data-elementor-lightbox-title=\"8\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjMyNSwidXJsIjoiaHR0cHM6XC9cL29ubGluZS1hcHBsaWNhdGlvbi5jby5pblwvc2NpZVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDRcLzgtNy5wbmciLCJzbGlkZXNob3ciOiI5MmRmZDBhIn0%3D\" href='https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/8-7.png'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/8-7.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/8-7.png 640w, https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/8-7-300x200.png 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"92dfd0a\" data-elementor-lightbox-title=\"6\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjMyMiwidXJsIjoiaHR0cHM6XC9cL29ubGluZS1hcHBsaWNhdGlvbi5jby5pblwvc2NpZVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDRcLzYtMTEucG5nIiwic2xpZGVzaG93IjoiOTJkZmQwYSJ9\" href='https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/6-11.png'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/6-11.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/6-11.png 640w, https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/6-11-300x200.png 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"92dfd0a\" data-elementor-lightbox-title=\"3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjMxOSwidXJsIjoiaHR0cHM6XC9cL29ubGluZS1hcHBsaWNhdGlvbi5jby5pblwvc2NpZVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDRcLzMtMTQucG5nIiwic2xpZGVzaG93IjoiOTJkZmQwYSJ9\" href='https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/3-14.png'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/3-14.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/3-14.png 640w, https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/3-14-300x200.png 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"92dfd0a\" data-elementor-lightbox-title=\"4\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjMyMCwidXJsIjoiaHR0cHM6XC9cL29ubGluZS1hcHBsaWNhdGlvbi5jby5pblwvc2NpZVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDRcLzQtMTMucG5nIiwic2xpZGVzaG93IjoiOTJkZmQwYSJ9\" href='https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/4-13.png'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/4-13.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/4-13.png 640w, https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/4-13-300x200.png 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"92dfd0a\" data-elementor-lightbox-title=\"2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjMxOCwidXJsIjoiaHR0cHM6XC9cL29ubGluZS1hcHBsaWNhdGlvbi5jby5pblwvc2NpZVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDRcLzItMTQucG5nIiwic2xpZGVzaG93IjoiOTJkZmQwYSJ9\" href='https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/2-14.png'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/2-14.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/2-14.png 640w, https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/2-14-300x200.png 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"92dfd0a\" data-elementor-lightbox-title=\"9\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjMyNCwidXJsIjoiaHR0cHM6XC9cL29ubGluZS1hcHBsaWNhdGlvbi5jby5pblwvc2NpZVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDRcLzktNi5wbmciLCJzbGlkZXNob3ciOiI5MmRmZDBhIn0%3D\" href='https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/9-6.png'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/9-6.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/9-6.png 640w, https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/9-6-300x200.png 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"92dfd0a\" data-elementor-lightbox-title=\"1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjMxNywidXJsIjoiaHR0cHM6XC9cL29ubGluZS1hcHBsaWNhdGlvbi5jby5pblwvc2NpZVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDRcLzEtMTQucG5nIiwic2xpZGVzaG93IjoiOTJkZmQwYSJ9\" href='https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/1-14.png'><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/1-14.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/1-14.png 640w, https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/1-14-300x200.png 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13f3282 e-con-full e-flex e-con e-parent\" data-id=\"13f3282\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a226a06 elementor-widget elementor-widget-html\" data-id=\"a226a06\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<script>\ndocument.querySelector(\"#page_title h2\").innerText =\"International Students' Day - Cultural Dance Competition\";\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Home \/ Life @Symbiosis \/ International Students&#8217; Day &#8211; Cultural Dance Competition<\/p>\n","protected":false},"author":1,"featured_media":6325,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-6309","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"\n<title>International Students&#039; Day - Cultural Dance Competition - Best International University in India - Symbiosis Pune<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/online-application.co.in\/scie\/events-details-95\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"International Students&#039; Day - Cultural Dance Competition - Best International University in India - Symbiosis Pune\" \/>\n<meta property=\"og:description\" content=\"Home \/ Life @Symbiosis \/ International Students&#8217; Day &#8211; Cultural Dance Competition\" \/>\n<meta property=\"og:url\" content=\"https:\/\/online-application.co.in\/scie\/events-details-95\/\" \/>\n<meta property=\"og:site_name\" content=\"Best International University in India - Symbiosis Pune\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T10:17:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/8-7.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/online-application.co.in\/scie\/events-details-95\/\",\"url\":\"https:\/\/online-application.co.in\/scie\/events-details-95\/\",\"name\":\"International Students' Day - Cultural Dance Competition - Best International University in India - Symbiosis Pune\",\"isPartOf\":{\"@id\":\"https:\/\/online-application.co.in\/scie\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/online-application.co.in\/scie\/events-details-95\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/online-application.co.in\/scie\/events-details-95\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/8-7.png\",\"datePublished\":\"2025-04-17T07:35:04+00:00\",\"dateModified\":\"2025-08-29T10:17:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/online-application.co.in\/scie\/events-details-95\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/online-application.co.in\/scie\/events-details-95\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/online-application.co.in\/scie\/events-details-95\/#primaryimage\",\"url\":\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/8-7.png\",\"contentUrl\":\"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/8-7.png\",\"width\":640,\"height\":426},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/online-application.co.in\/scie\/events-details-95\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/online-application.co.in\/scie\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"International Students&#8217; Day &#8211; Cultural Dance Competition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/online-application.co.in\/scie\/#website\",\"url\":\"https:\/\/online-application.co.in\/scie\/\",\"name\":\"Best International University in India - Symbiosis Pune\",\"description\":\"Symbiosis is acclaimed as the best international university in India that provides UG and PG degree courses, attracting students from across the globe. Find more\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/online-application.co.in\/scie\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n","yoast_head_json":{"title":"International Students' Day - Cultural Dance Competition - Best International University in India - Symbiosis Pune","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/online-application.co.in\/scie\/events-details-95\/","og_locale":"en_US","og_type":"article","og_title":"International Students' Day - Cultural Dance Competition - Best International University in India - Symbiosis Pune","og_description":"Home \/ Life @Symbiosis \/ International Students&#8217; Day &#8211; Cultural Dance Competition","og_url":"https:\/\/online-application.co.in\/scie\/events-details-95\/","og_site_name":"Best International University in India - Symbiosis Pune","article_modified_time":"2025-08-29T10:17:46+00:00","og_image":[{"width":640,"height":426,"url":"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/8-7.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/online-application.co.in\/scie\/events-details-95\/","url":"https:\/\/online-application.co.in\/scie\/events-details-95\/","name":"International Students' Day - Cultural Dance Competition - Best International University in India - Symbiosis Pune","isPartOf":{"@id":"https:\/\/online-application.co.in\/scie\/#website"},"primaryImageOfPage":{"@id":"https:\/\/online-application.co.in\/scie\/events-details-95\/#primaryimage"},"image":{"@id":"https:\/\/online-application.co.in\/scie\/events-details-95\/#primaryimage"},"thumbnailUrl":"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/8-7.png","datePublished":"2025-04-17T07:35:04+00:00","dateModified":"2025-08-29T10:17:46+00:00","breadcrumb":{"@id":"https:\/\/online-application.co.in\/scie\/events-details-95\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/online-application.co.in\/scie\/events-details-95\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/online-application.co.in\/scie\/events-details-95\/#primaryimage","url":"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/8-7.png","contentUrl":"https:\/\/online-application.co.in\/scie\/wp-content\/uploads\/2025\/04\/8-7.png","width":640,"height":426},{"@type":"BreadcrumbList","@id":"https:\/\/online-application.co.in\/scie\/events-details-95\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/online-application.co.in\/scie\/"},{"@type":"ListItem","position":2,"name":"International Students&#8217; Day &#8211; Cultural Dance Competition"}]},{"@type":"WebSite","@id":"https:\/\/online-application.co.in\/scie\/#website","url":"https:\/\/online-application.co.in\/scie\/","name":"Best International University in India - Symbiosis Pune","description":"Symbiosis is acclaimed as the best international university in India that provides UG and PG degree courses, attracting students from across the globe. Find more","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/online-application.co.in\/scie\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/online-application.co.in\/scie\/wp-json\/wp\/v2\/pages\/6309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/online-application.co.in\/scie\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/online-application.co.in\/scie\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/online-application.co.in\/scie\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/online-application.co.in\/scie\/wp-json\/wp\/v2\/comments?post=6309"}],"version-history":[{"count":5,"href":"https:\/\/online-application.co.in\/scie\/wp-json\/wp\/v2\/pages\/6309\/revisions"}],"predecessor-version":[{"id":13046,"href":"https:\/\/online-application.co.in\/scie\/wp-json\/wp\/v2\/pages\/6309\/revisions\/13046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/online-application.co.in\/scie\/wp-json\/wp\/v2\/media\/6325"}],"wp:attachment":[{"href":"https:\/\/online-application.co.in\/scie\/wp-json\/wp\/v2\/media?parent=6309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 69b2aa38190636a5228af809. Config Timestamp: 2026-03-12 11:57:43 UTC, Cached Timestamp: 2026-05-13 19:31:22 UTC -->